{"id":352,"date":"2011-07-07T15:30:16","date_gmt":"2011-07-07T15:30:16","guid":{"rendered":"http:\/\/www.deportechihuahua.com.mx\/1\/noticias\/voly\/lo-mejor-de-la-copa-el-publico-y-la-ciudad-entrenadores-de-selecciones\/"},"modified":"2011-07-07T15:30:16","modified_gmt":"2011-07-07T15:30:16","slug":"lo-mejor-de-la-copa-el-publico-y-la-ciudad-entrenadores-de-selecciones","status":"publish","type":"post","link":"https:\/\/www.deportechihuahua.com.mx\/1\/archivos\/352","title":{"rendered":"LO MEJOR DE LA COPA, EL P\u00daBLICO Y LA CIUDAD; ENTRENADORES DE SELECCIONES"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"TEXT-ALIGN: justify; MARGIN: 0cm 0cm 10pt\"><span style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Arial','sans-serif'; FONT-SIZE: 10pt\" lang=\"ES\">\u00a0<\/span>\u00a0<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-351\" src=\"https:\/\/www.deportechihuahua.com.mx\/1\/wp-content\/uploads\/2011\/07\/entrenadores.jpg\" border=\"0\" width=\"460\" height=\"315\" srcset=\"https:\/\/www.deportechihuahua.com.mx\/1\/wp-content\/uploads\/2011\/07\/entrenadores.jpg 460w, https:\/\/www.deportechihuahua.com.mx\/1\/wp-content\/uploads\/2011\/07\/entrenadores-300x205.jpg 300w\" sizes=\"auto, (max-width: 460px) 100vw, 460px\" \/><\/p>\n<p class=\"MsoNormal\" style=\"TEXT-ALIGN: justify; MARGIN: 0cm 0cm 10pt\">\u00a0<\/p>\n<p>\u00a0<\/p>\n<p \/><span style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Arial','sans-serif'; FONT-SIZE: 10pt\" lang=\"ES\" \/><span style=\"color: #000000;\" \/>Para los entrenadores de los equipos que participan en la X Copa Panamericana de Voleibol Femenil en Ciudad Ju\u00e1rez, la calidez del p\u00fablico asistente, genera un ambiente \u00fanico en los partidos que los compromete a brindar un buen espect\u00e1culo deportivo.   <!--more-->  <span style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Arial','sans-serif'; FONT-SIZE: 10pt\" lang=\"ES\"><span style=\"color: #000000;\"> <\/p>\n<p class=\"MsoNormal\" style=\"TEXT-ALIGN: justify; MARGIN: 0cm 0cm 10pt\">\u00a0<\/p>\n<p> <\/span><\/span><\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"TEXT-ALIGN: justify; MARGIN: 0cm 0cm 10pt\">\u00a0<\/p>\n<p class=\"MsoNormal\" style=\"TEXT-ALIGN: justify; MARGIN: 0cm 0cm 10pt\"><span style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Arial','sans-serif'; FONT-SIZE: 10pt\" lang=\"ES\"><span style=\"color: #000000;\">Hugo J\u00e1uregui cabeza del conjunto chileno, destac\u00f3 el \u00e9xito de la Copa, gracias a que el Comit\u00e9 Organizador se preocup\u00f3 por que este evento tuviera el verdadero valor que representa; \u201cHan sido muy cuidadosos con todos los detalles, la log\u00edstica y el trato han sido fenomenales, es la primera ocasi\u00f3n que estamos ac\u00e1 en Ju\u00e1rez, nos parece grandioso el p\u00fablico, estamos muy complacidos\u201d, extern\u00f3.<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"TEXT-ALIGN: justify; MARGIN: 0cm 0cm 10pt\"><span style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Arial','sans-serif'; FONT-SIZE: 10pt\" lang=\"ES\"><span style=\"color: #000000;\">Por su parte el entrenador de Canad\u00e1, se\u00f1al\u00f3, \u201cEl hotel, la comida, las facilidades han sido impresionantes, pero lo mejor es haber jugado con miles personas en cada partido\u201d, finaliz\u00f3 Arnd Ludwig.<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"TEXT-ALIGN: justify; MARGIN: 0cm 0cm 10pt\"><span style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Arial','sans-serif'; FONT-SIZE: 10pt\" lang=\"ES\"><span style=\"color: #000000;\">Para el dirigente de Rep\u00fablica Dominicana, Marcos Kwiek mostr\u00f3 su felicidad ante la organizaci\u00f3n de esta Copa; \u201cEstamos muy contentos, no hemos tenido ning\u00fan inconveniente, al contrario la gente ha sido muy amable por todos lados, los fan\u00e1ticos, llegamos con un pensamiento de disfrutarlo y la ciudad nos abrig\u00f3 muy bien\u201d.<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"TEXT-ALIGN: justify; MARGIN: 0cm 0cm 10pt\"><span style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Arial','sans-serif'; FONT-SIZE: 10pt\" lang=\"ES\"><span style=\"color: #000000;\">Mientras tanto el coach de Cuba, Juan Carlos Gala coment\u00f3; \u201cHemos visto que Ju\u00e1rez ha hecho este torneo con mucho cari\u00f1o, la atenci\u00f3n, la preocupaci\u00f3n en todo momento, las canchas de entrenamiento perfectas, han sido una sede digna y ojal\u00e1 sigan organizando eventos\u201d.<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"TEXT-ALIGN: justify; MARGIN: 0cm 0cm 10pt\"><span style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Arial','sans-serif'; FONT-SIZE: 10pt\" lang=\"ES\"><span style=\"color: #000000;\">\u201cEl p\u00fablico ha sido \u00fanico, es dif\u00edcil encontrar un p\u00fablico as\u00ed, disfruta de las jugadas, valora el nivel de cada selecci\u00f3n, por momento le vitorean a Cuba, en otras a Dominicana, Argentina, aplauden las grandes acciones, viene a disfrutar el espect\u00e1culo, han sido el mejor p\u00fablico que hemos tenido\u201d, finaliz\u00f3.<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"TEXT-ALIGN: justify; MARGIN: 0cm 0cm 10pt\"><span style=\"LINE-HEIGHT: 115%; FONT-FAMILY: 'Arial','sans-serif'; FONT-SIZE: 10pt\" lang=\"ES\"><span style=\"color: #000000;\">Este d\u00eda todas las delegaciones disfrutaron de un merecido descanso y ahora se preparan para la segunda fase de este torneo, que se reactiva este jueves en los mismos escenarios deportivos, Gimnasio de la UACJ y del COBACH.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a0 \u00a0 \u00a0 Para los entrenadores de los equipos que participan en la X Copa Panamericana de Voleibol Femenil en Ciudad Ju\u00e1rez, la calidez del p\u00fablico asistente, genera un ambiente \u00fanico en los partidos que los compromete a brindar un buen espect\u00e1culo deportivo.<\/p>\n","protected":false},"author":1,"featured_media":351,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"class_list":["post-352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-voly"],"_links":{"self":[{"href":"https:\/\/www.deportechihuahua.com.mx\/1\/wp-json\/wp\/v2\/posts\/352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deportechihuahua.com.mx\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deportechihuahua.com.mx\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deportechihuahua.com.mx\/1\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deportechihuahua.com.mx\/1\/wp-json\/wp\/v2\/comments?post=352"}],"version-history":[{"count":0,"href":"https:\/\/www.deportechihuahua.com.mx\/1\/wp-json\/wp\/v2\/posts\/352\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deportechihuahua.com.mx\/1\/wp-json\/wp\/v2\/media\/351"}],"wp:attachment":[{"href":"https:\/\/www.deportechihuahua.com.mx\/1\/wp-json\/wp\/v2\/media?parent=352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deportechihuahua.com.mx\/1\/wp-json\/wp\/v2\/categories?post=352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deportechihuahua.com.mx\/1\/wp-json\/wp\/v2\/tags?post=352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}